{"id":50738,"date":"2021-12-21T16:21:14","date_gmt":"2021-12-21T16:21:14","guid":{"rendered":"http:\/\/noticiastres.com\/?p=50738"},"modified":"2023-12-13T15:26:02","modified_gmt":"2023-12-13T15:26:02","slug":"merlo-cierre-de-ano-de-servidores-comunitarios","status":"publish","type":"post","link":"https:\/\/noticiastres.com\/index.php\/2021\/12\/21\/merlo-cierre-de-ano-de-servidores-comunitarios\/","title":{"rendered":"MERLO: CIERRE DE A\u00d1O DE SERVIDORES COMUNITARIOS"},"content":{"rendered":"\n<p>Para celebrar el trabajo realizado durante el a\u00f1o, la&nbsp;Secretar\u00eda de Desarrollo e Integraci\u00f3n Social de Merlo organiz\u00f3 un encuentro a modo de cierre anual con referentes barriales, de comedores, merenderos y de espacios comunitarios del distrito en el Parque Municipal N\u00e9stor Kirchner.<\/p>\n\n\n\n<p>En la jornada se realiz\u00f3 un balance del trabajo hecho en el a\u00f1o junto a las actividades y programas que impulsa la Secretar\u00eda de Desarrollo Social en beneficio de la comunidad y de los sectores m\u00e1s vulnerables de Merlo.<\/p>\n\n\n\n<p>La Intendenta Interina Karina Men\u00e9ndez acompa\u00f1\u00f3 e hizo un balance del trabajo de los Servidores Comunitarios en el contexto de pandemia: \u201cLos Servidores son la columna vertebral de la Secretar\u00eda de Desarrollo Social. Durante la pandemia, ellos abrieron las puertas de los comedores a cualquier vecino, en todo horario, y eso es algo m\u00e1s que destacable\u201d.<\/p>\n\n\n\n<p>Asimismo, la jefa comunal destac\u00f3: \u201cSin los Servidores ser\u00eda muy dif\u00edcil llegar a los barrios. Son la \u00fanica herramienta que tenemos para poder llegar a cada vecino y a cada familia. Sin su ayuda, y sin la ayuda de las manzaneras, de los clubes y de las iglesias, hubiera sido imposible en este contexto actual. Siempre voy a estar agradecida con cada uno de ellos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para celebrar el trabajo realizado durante el a\u00f1o, la&nbsp;Secretar\u00eda de Desarrollo e Integraci\u00f3n Social de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":50739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[124],"tags":[1274,1542,125,382,456,2834,724],"class_list":["post-50738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad-merlo","tag-cierre-de-ano","tag-karina-menendez-2","tag-merlo","tag-municipalidad-de-merlo","tag-municipio-de-merlo","tag-secretaria-de-desarrollo-e-integracion-social-3","tag-servidores-comunitarios"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/noticiastres.com\/wp-content\/uploads\/2021\/12\/servidorescomunitarios-2.jpg?fit=1200%2C675&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/posts\/50738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/comments?post=50738"}],"version-history":[{"count":1,"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/posts\/50738\/revisions"}],"predecessor-version":[{"id":50740,"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/posts\/50738\/revisions\/50740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/media\/50739"}],"wp:attachment":[{"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/media?parent=50738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/categories?post=50738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiastres.com\/index.php\/wp-json\/wp\/v2\/tags?post=50738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}